{"id":3023,"date":"2021-05-31T09:53:38","date_gmt":"2021-05-31T07:53:38","guid":{"rendered":"https:\/\/teamtex.it\/cms\/?p=3023"},"modified":"2022-01-16T11:56:49","modified_gmt":"2022-01-16T10:56:49","slug":"sui-pedali-con-il-nuovo-kit","status":"publish","type":"post","link":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/","title":{"rendered":"Sui pedali con il nuovo kit!"},"content":{"rendered":"<div>\n<div>\n<div dir=\"auto\">\n<div style=\"text-align: left;\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\"><b>Con l&#8217;arrivo della stagione estiva, i nostri atleti, ultracycler, cicloamatori hanno sfoggiato le nuove divise per la stagione 2021; anche quest&#8217;anno creati dai fratelli Alborghetti del Maglificio ROSTI.<\/b><br \/>\nGrazie alla professionalit\u00e0 e alla precisione sartoriale di @<a href=\"http:\/\/rosti.it\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/rosti.it&amp;source=gmail&amp;ust=1642416195281000&amp;usg=AOvVaw3frPJ7e15HAmWeXhqg5QRF\">rosti.it<\/a>\u00a0, fornitore ufficiale di team UCI World Tour e UCI Pro Team, i nostri tesserati possono indossare un perfomante completo, che consetir\u00e0 loro di esprimere la miglior prestazione con stile, grazie al design moderno, che vede rinnovato il logo TEAM TEX, mantenendo i tradizionali colori sociali: il giallo della maglia del Tour de France con l&#8217;eleganza del nero.<i>\u00a0Nella gallery sul sito\u00a0<a href=\"http:\/\/www.teamtex.it\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.teamtex.it&amp;source=gmail&amp;ust=1642416195281000&amp;usg=AOvVaw1qEsQbU_GgHPcXeMh2BCg-\">www.teamtex.it<\/a>\u00a0potete vedere le prime immagini dei nostri TEXraiders con il nuovo kit!<\/i><\/div>\n<\/div>\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div>\n<div dir=\"auto\">\n<div style=\"text-align: left;\">\n<div dir=\"auto\">\n<div>\n<div dir=\"auto\">\n<blockquote>\n<div dir=\"auto\"><\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">Ben visibili sulle divise sono i loghi dei\u00a0<b>nostri sponsor<\/b>, che ringraziamo per la loro fiducia e con cui ci auguriamo di raggiungere importanti traguardi in questo 2021:\u00a0<b>RIECO Office Solution<\/b>\u00a0di Finazzi Giovanni,\u00a0<b>T.M.P. Trasformazione di Materie Plastiche<\/b>\u00a0di Bacis Manuel,\u00a0<b>NEMBRINI Group Tecnologie per l&#8217;elettricit\u00e0<\/b>\u00a0di Nembrini Massimo,\u00a0<b>MABO Bottoni e accessori abbigliamento<\/b>\u00a0dei Fratelli Signorelli Agostino con Luigi e Adriano,<b>\u00a0PERSONAL UFFICIO SERVICE Vendita e assistenza Hardware e software<\/b>\u00a0dei fratelli Monieri Michele e Simone,\u00a0<b>BIERRE AUTO Officina e concessionaria multimarca<\/b>\u00a0di Roberto, Loris Rottoli e Bressanini Massimo,\u00a0<b>CENTRO MEDICO SPORTIVO LORETO NOVE<\/b>\u00a0del Dott.Mantovani Massimiliano e Dott.Molinello Alessandro,\u00a0<b>ONORANZE FUNEBRI Gozzini Tiziano<\/b>\u00a0ed il nostro sponsor tecnico\u00a0<b>Giograf design<\/b>\u00a0di Capoferri Giovanni.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div dir=\"auto\">\n<blockquote>\n<div dir=\"auto\"><\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div>\n<div dir=\"auto\">Sul nostro sito\u00a0<a href=\"http:\/\/www.teamtex.it\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.teamtex.it&amp;source=gmail&amp;ust=1642416195281000&amp;usg=AOvVaw1qEsQbU_GgHPcXeMh2BCg-\">www.teamtex.it<\/a>\u00a0nella pagina SPONSOR 2021 potete trovare i rispettivi collegamenti per conoscergli e apprezzare la loro forza e specifica professionalit\u00e0.<br \/>\nSi avvicina la data della manifestazione che, con il gruppo Free Time di Telgate e gli amici del Centro Sportivo di Telgate, abbiamo organizzato con tanta passione, nonostante le difficolta del momento ed inserito nel calendario della FCI: La terza edizione de<i>\u00a0<\/i><b><i>\u201cLA 111 \u2013 Ciclopedalata tra i castelli\u201d.<\/i>\u00a0Domenica 27 giugno<\/b>\u00a0dalle 7:30 alle 8:30 si terr\u00e0 la partenza &#8220;alla francese&#8221; ed i partecipanti potranno scegliere su quale, dei tre rinnovati percorsi, pedalare; Tutti lontani dal traffico e in uno splendido percorso naturale, che nel lungo vi porter\u00e0 a toccare ben 8 spettacolari castelli.<br \/>\nAl sito\u00a0<a href=\"http:\/\/www.la111.it\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.la111.it&amp;source=gmail&amp;ust=1642416195282000&amp;usg=AOvVaw3zAD380GFgjqNtl-irvUcc\">www.la111.it<\/a>\u00a0nella pagina i tre percorsi, potrete visualizzare le piantine di ognuno dei percorsi, e grazia alla traccia caricata su\u00a0<a href=\"http:\/\/ridewithgps.it\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/ridewithgps.it&amp;source=gmail&amp;ust=1642416195282000&amp;usg=AOvVaw1RRjjceULIBfrgI45weCB7\">ridewithgps.it<\/a>\u00a0cliccando sulla cartina potrete addirittura addentrarvi nel percorso e visualizzandolo in anteprima, metro dopo metro.<i><b>\u00a0Non solo una domenica sui pedali<\/b><\/i>, divertendosi in sicurezza, ma con l&#8217;iscrizione alla manifestazione si potr\u00e0 contribuire alla ricerca contro i tumori cerebrali sostenendo la\u00a0<b>Fondazione Giovanni Celeghin ONLUS.<\/b><\/p>\n<\/div>\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div>\n<div dir=\"auto\">\n<div style=\"text-align: left;\">\n<div dir=\"auto\">\n<div>\n<div dir=\"auto\">\n<blockquote>\n<div dir=\"auto\"><\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"auto\">Nel prossimo comunicato vi presenteremo il calendario delle manifestazioni a cui i nostri tesserati prenderanno parte, e nel frattempo ci complimentiamo con i nostri due infaticabili pedalatori\u00a0<b>Zanchi Giliola<\/b>\u00a0e\u00a0<b>Pellegrino Michele<\/b>\u00a0che proprio la scorsa domenica hanno portato a termine la prima impresa del 2021: la randonn\u00e9e\u00a0<i><b>&#8220;Edelweiss 2021&#8221;<\/b><\/i>: con partenza ed arrivo da Faedo (TN) percorrendo con altri 150 ultracycler un totale di 421 km e 4000 d+ sempre sui pedali !<\/p>\n<div dir=\"auto\">\n<div dir=\"auto\">\n<div>\n<div dir=\"auto\">\n<div style=\"text-align: left;\">\n<div dir=\"auto\">\n<div>\n<div dir=\"auto\">\n<blockquote>\n<div dir=\"auto\"><\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div dir=\"auto\">\n<blockquote>\n<div dir=\"auto\"><i><b>La presidentessa del team TEX Frederyca con Valerio Tebaldi augurano a tutti gli atleti e sponsor una felice estate in bicicletta!<\/b><\/i><\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div dir=\"auto\">\n<div dir=\"auto\"><strong><em>\u00a0Non perdetevi le nostre ruote &#8220;social\u201d :\u00a0<\/em><\/strong><strong>Seguiteci e fateci seguire<\/strong> sul profilo Instagram<a href=\"https:\/\/www.instagram.com\/teamtex\/\"> @teamtex<\/a> dove trovate le immagini dei nostri <strong>#texraiders<\/strong> e alla pagina Facebook<a href=\"https:\/\/www.facebook.com\/teamTEX.ASD\/\"> @teamTEX.ASD<\/a><br \/>\n<strong>#IoVadoInBici<\/strong><br \/>\n<strong>#teamtex<\/strong><\/div>\n<blockquote>\n<div dir=\"auto\"><\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<div><b><a href=\"https:\/\/teamtex.it\/cms\/sponsor-2021\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/teamtex.it\/cms\/sponsor-2020\/&amp;source=gmail&amp;ust=1611481181566000&amp;usg=AFQjCNF5NZUw1T1Fd8kTxsteJINVX4sfqQ\">&gt;&gt; Conosci i nostri sponsor 2021<\/a><\/b><\/div>\n<div><a href=\"https:\/\/teamtex.it\/cms\/gallery\/alla-111-il-raduno-dei-texraiders\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/teamtex.it\/cms\/gallery\/alla-111-il-raduno-dei-texraiders\/&amp;source=gmail&amp;ust=1642416193311000&amp;usg=AOvVaw00rpWQvhjYtu1b1NrotuS_\"><b><a href=\"https:\/\/teamtex.it\/cms\/gallery\/team-tex-2021-cyclings-kit\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/teamtex.it\/cms\/gallery\/team-tex-2021-cyclings-kit\/&amp;source=gmail&amp;ust=1642416195282000&amp;usg=AOvVaw1VjHcxOzJSwMhY_EWnoIrp\">&gt;&gt; Guarda la gallery con le nuove divise 2021<\/a><\/b><\/a><\/div>\n<div><b><a href=\"https:\/\/www.instagram.com\/teamtex\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.instagram.com\/teamtex\/&amp;source=gmail&amp;ust=1611481181566000&amp;usg=AFQjCNHr0HQoFb6tUqByh7wyc9kzmnYUiQ\">&gt;&gt; Visita il nostro profilo Instagram !<\/a><\/b><\/div>\n<\/div>\n<div>\n<div><a href=\"https:\/\/www.facebook.com\/teamTEX.ASD\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.facebook.com\/teamTEX.ASD\/&amp;source=gmail&amp;ust=1611481181566000&amp;usg=AFQjCNGBF9R-D661iFcUrxtOMej52j-H7g\"><b>&gt;&gt; Visita la nostra pagina facebook !<\/b><\/a><\/div>\n<blockquote>\n<div><\/div>\n<\/blockquote>\n<div><b class=\"first-child\"><span class=\"last-child first-child\">A.<\/span><\/b><b class=\"last-child\"><span class=\"last-child first-child\">S.D. Team TEX, v<\/span><\/b><span class=\"last-child first-child\"><b class=\"last-child first-child\">ia Brigata Lupi di Toscana, 15 Chiuduno (Bg)<\/b><\/span><\/div>\n<\/div>\n<\/div>\n<p><span class=\"first-child\"><b class=\"last-child first-child\"><a class=\"last-child first-child\" href=\"mailto:ufficiostampa.teamtex@gmail.com\" target=\"_blank\" rel=\"noopener noreferrer\" data-slimstat=\"5\">ufficiostampa.teamtex@<wbr class=\"last-child first-child\" \/>gmail.com<\/a><\/b><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con l&#8217;arrivo della stagione estiva, i nostri atleti, ultracycler, cicloamatori hanno sfoggiato le nuove divise per la stagione 2021; anche quest&#8217;anno creati dai fratelli Alborghetti del Maglificio ROSTI. Grazie alla<\/p>\n","protected":false},"author":3,"featured_media":3024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,43,34,15],"tags":[85,37,73,76,60,51,91,53,77,25,58,59],"class_list":["post-3023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amatori","category-mountain-bike","category-strada","category-team-tex","tag-bikers","tag-ciclismo","tag-cicloamatori","tag-ciclopedalatatraicastelli","tag-cyclingteam","tag-fci","tag-granfondo","tag-inlombardia","tag-la111","tag-randonee","tag-teamtex","tag-texraiders"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sui pedali con il nuovo kit! - TEAM TEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sui pedali con il nuovo kit! - TEAM TEX\" \/>\n<meta property=\"og:description\" content=\"Con l&#8217;arrivo della stagione estiva, i nostri atleti, ultracycler, cicloamatori hanno sfoggiato le nuove divise per la stagione 2021; anche quest&#8217;anno creati dai fratelli Alborghetti del Maglificio ROSTI. Grazie alla\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/\" \/>\n<meta property=\"og:site_name\" content=\"TEAM TEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/teamTEX.ASD\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-31T07:53:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-16T10:56:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teamtex.it\/cms\/wp-content\/uploads\/2022\/01\/TeamTEX_08ALTO_2021-02_608x250.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"608\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teamtex\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"teamtex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/\",\"url\":\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/\",\"name\":\"Sui pedali con il nuovo kit! - TEAM TEX\",\"isPartOf\":{\"@id\":\"https:\/\/teamtex.it\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teamtex.it\/cms\/wp-content\/uploads\/2022\/01\/TeamTEX_08ALTO_2021-02_608x250.jpg\",\"datePublished\":\"2021-05-31T07:53:38+00:00\",\"dateModified\":\"2022-01-16T10:56:49+00:00\",\"author\":{\"@id\":\"https:\/\/teamtex.it\/cms\/#\/schema\/person\/c6de176dbc13e8823f477456eea7b991\"},\"breadcrumb\":{\"@id\":\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#primaryimage\",\"url\":\"https:\/\/teamtex.it\/cms\/wp-content\/uploads\/2022\/01\/TeamTEX_08ALTO_2021-02_608x250.jpg\",\"contentUrl\":\"https:\/\/teamtex.it\/cms\/wp-content\/uploads\/2022\/01\/TeamTEX_08ALTO_2021-02_608x250.jpg\",\"width\":608,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/teamtex.it\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sui pedali con il nuovo kit!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teamtex.it\/cms\/#website\",\"url\":\"https:\/\/teamtex.it\/cms\/\",\"name\":\"TEAM TEX\",\"description\":\"A.S.D. TEAM TEX\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teamtex.it\/cms\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/teamtex.it\/cms\/#\/schema\/person\/c6de176dbc13e8823f477456eea7b991\",\"name\":\"teamtex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/teamtex.it\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/372a21a9c95239444ec0d17f3042dee8aa8a44f3ac5d5c24c1820b34c8213f8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/372a21a9c95239444ec0d17f3042dee8aa8a44f3ac5d5c24c1820b34c8213f8a?s=96&d=mm&r=g\",\"caption\":\"teamtex\"},\"url\":\"https:\/\/teamtex.it\/cms\/author\/teamtex\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sui pedali con il nuovo kit! - TEAM TEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/","og_locale":"it_IT","og_type":"article","og_title":"Sui pedali con il nuovo kit! - TEAM TEX","og_description":"Con l&#8217;arrivo della stagione estiva, i nostri atleti, ultracycler, cicloamatori hanno sfoggiato le nuove divise per la stagione 2021; anche quest&#8217;anno creati dai fratelli Alborghetti del Maglificio ROSTI. Grazie alla","og_url":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/","og_site_name":"TEAM TEX","article_publisher":"https:\/\/www.facebook.com\/teamTEX.ASD\/","article_published_time":"2021-05-31T07:53:38+00:00","article_modified_time":"2022-01-16T10:56:49+00:00","og_image":[{"width":608,"height":250,"url":"https:\/\/teamtex.it\/cms\/wp-content\/uploads\/2022\/01\/TeamTEX_08ALTO_2021-02_608x250.jpg","type":"image\/jpeg"}],"author":"teamtex","twitter_misc":{"Scritto da":"teamtex","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/","url":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/","name":"Sui pedali con il nuovo kit! - TEAM TEX","isPartOf":{"@id":"https:\/\/teamtex.it\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#primaryimage"},"image":{"@id":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#primaryimage"},"thumbnailUrl":"https:\/\/teamtex.it\/cms\/wp-content\/uploads\/2022\/01\/TeamTEX_08ALTO_2021-02_608x250.jpg","datePublished":"2021-05-31T07:53:38+00:00","dateModified":"2022-01-16T10:56:49+00:00","author":{"@id":"https:\/\/teamtex.it\/cms\/#\/schema\/person\/c6de176dbc13e8823f477456eea7b991"},"breadcrumb":{"@id":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#primaryimage","url":"https:\/\/teamtex.it\/cms\/wp-content\/uploads\/2022\/01\/TeamTEX_08ALTO_2021-02_608x250.jpg","contentUrl":"https:\/\/teamtex.it\/cms\/wp-content\/uploads\/2022\/01\/TeamTEX_08ALTO_2021-02_608x250.jpg","width":608,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/teamtex.it\/cms\/sui-pedali-con-il-nuovo-kit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teamtex.it\/cms\/"},{"@type":"ListItem","position":2,"name":"Sui pedali con il nuovo kit!"}]},{"@type":"WebSite","@id":"https:\/\/teamtex.it\/cms\/#website","url":"https:\/\/teamtex.it\/cms\/","name":"TEAM TEX","description":"A.S.D. TEAM TEX","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teamtex.it\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/teamtex.it\/cms\/#\/schema\/person\/c6de176dbc13e8823f477456eea7b991","name":"teamtex","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/teamtex.it\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/372a21a9c95239444ec0d17f3042dee8aa8a44f3ac5d5c24c1820b34c8213f8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/372a21a9c95239444ec0d17f3042dee8aa8a44f3ac5d5c24c1820b34c8213f8a?s=96&d=mm&r=g","caption":"teamtex"},"url":"https:\/\/teamtex.it\/cms\/author\/teamtex\/"}]}},"_links":{"self":[{"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/posts\/3023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/comments?post=3023"}],"version-history":[{"count":0,"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/posts\/3023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/media\/3024"}],"wp:attachment":[{"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/media?parent=3023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/categories?post=3023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teamtex.it\/cms\/wp-json\/wp\/v2\/tags?post=3023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}